{"id":279,"date":"2020-12-05T07:33:00","date_gmt":"2020-12-05T07:33:00","guid":{"rendered":"http:\/\/melisaloza.com\/?post_type=rara-portfolio&#038;p=279"},"modified":"2021-01-25T19:25:40","modified_gmt":"2021-01-25T19:25:40","slug":"couple-illustration","status":"publish","type":"rara-portfolio","link":"https:\/\/melisaloza.com\/index.php\/portfolio\/couple-illustration\/","title":{"rendered":"Couple Illustration"},"content":{"rendered":"\n<p>Open for portraits comission. Each new portrait is a chance to portray new personalities and experiment with different styles. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-768x1024.jpg\" alt=\"Couple Illustration Living Room\" class=\"wp-image-281\" srcset=\"https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-768x1024.jpg 768w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-225x300.jpg 225w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-1152x1536.jpg 1152w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-1536x2048.jpg 1536w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-45x60.jpg 45w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-1024x678.jpg\" alt=\"Couple Illustration\" class=\"wp-image-282\" srcset=\"https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-1024x678.jpg 1024w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-300x199.jpg 300w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-768x508.jpg 768w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-1536x1017.jpg 1536w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-2048x1356.jpg 2048w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/07\/couple-illustration-zoom-91x60.jpg 91w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Open for portraits comission. Each new portrait is a chance to portray new personalities and experiment with different styles.<\/p>\n","protected":false},"author":1,"featured_media":280,"comment_status":"closed","ping_status":"closed","template":"","rara_portfolio_categories":[8],"class_list":["post-279","rara-portfolio","type-rara-portfolio","status-publish","has-post-thumbnail","hentry","rara_portfolio_categories-illustration"],"_links":{"self":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara-portfolio\/279"}],"collection":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara-portfolio"}],"about":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/types\/rara-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/comments?post=279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"rara_portfolio_categories","embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara_portfolio_categories?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}