{"id":184,"date":"2020-12-09T12:44:14","date_gmt":"2020-12-09T12:44:14","guid":{"rendered":"http:\/\/melisaloza.com\/?post_type=rara-portfolio&#038;p=184"},"modified":"2021-01-25T19:26:38","modified_gmt":"2021-01-25T19:26:38","slug":"royal-fellas","status":"publish","type":"rara-portfolio","link":"https:\/\/melisaloza.com\/index.php\/portfolio\/royal-fellas\/","title":{"rendered":"Royal Fellas"},"content":{"rendered":"\n<p>El equipo y marca Royal Fellas nace con la motivaci\u00f3n de aportar material de calidad a la escena del skateboarding, as\u00ed como de aunar el amplio imaginario visual a la que dicha escena urbana se ha visto expuesta a lo largo de varias generaciones, influenciada por el dise\u00f1o, la fotograf\u00eda y el arte el general.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-1024x678.jpg\" alt=\"Royal Fellas Skateboard sample\" class=\"wp-image-190\" srcset=\"https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-1024x678.jpg 1024w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-300x199.jpg 300w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-768x508.jpg 768w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-1536x1017.jpg 1536w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-2048x1356.jpg 2048w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf1-91x60.jpg 91w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-1024x678.jpg\" alt=\"Royal Fellas tshirs\" class=\"wp-image-193\" srcset=\"https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-1024x678.jpg 1024w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-300x199.jpg 300w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-768x508.jpg 768w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-1536x1017.jpg 1536w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-2048x1356.jpg 2048w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf2-91x60.jpg 91w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-1024x678.jpg\" alt=\"Royal Fellas Presentation\" class=\"wp-image-196\" srcset=\"https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-1024x678.jpg 1024w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-300x199.jpg 300w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-768x508.jpg 768w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-1536x1017.jpg 1536w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-2048x1356.jpg 2048w, https:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf3-91x60.jpg 91w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"http:\/\/melisaloza.com\/wp-content\/uploads\/2020\/06\/rf-animation.gif\" alt=\"Royal Fellas logo animation\" class=\"wp-image-191\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El equipo y marca Royal Fellas nace con la motivaci\u00f3n de aportar material de calidad a la escena del skateboarding, as\u00ed como de aunar el amplio imaginario visual a la que dicha escena urbana se ha visto expuesta a lo largo de varias generaciones, influenciada por el dise\u00f1o, la fotograf\u00eda y el arte el general.<\/p>\n","protected":false},"author":1,"featured_media":197,"comment_status":"closed","ping_status":"closed","template":"","rara_portfolio_categories":[6],"class_list":["post-184","rara-portfolio","type-rara-portfolio","status-publish","has-post-thumbnail","hentry","rara_portfolio_categories-branding"],"_links":{"self":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara-portfolio\/184"}],"collection":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara-portfolio"}],"about":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/types\/rara-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/comments?post=184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/media\/197"}],"wp:attachment":[{"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"rara_portfolio_categories","embeddable":true,"href":"https:\/\/melisaloza.com\/index.php\/wp-json\/wp\/v2\/rara_portfolio_categories?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}